{"id":12,"date":"2022-05-18T13:00:38","date_gmt":"2022-05-18T18:00:38","guid":{"rendered":"https:\/\/ipsucaldas.com\/Intranet\/login\/"},"modified":"2022-06-02T15:42:35","modified_gmt":"2022-06-02T20:42:35","slug":"login","status":"publish","type":"page","link":"https:\/\/ipsucaldas.com\/Intranet\/login\/","title":{"rendered":"Iniciar sesi\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12\" class=\"elementor elementor-12\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-624ffb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"624ffb1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cba75b4\" data-id=\"cba75b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dd27ae elementor-widget elementor-widget-heading\" data-id=\"6dd27ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inicio de sesi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-708f9c5 elementor-widget elementor-widget-text-editor\" data-id=\"708f9c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Inicia sesi\u00f3n para ingresar la Intranet de la Corporaci\u00f3n IPS <b>Universitaria de Caldas.\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d56ba8\" data-id=\"0d56ba8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aea273b elementor-widget elementor-widget-shortcode\" data-id=\"4aea273b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"um um-login um-6\">\n\t<div class=\"um-form\">\n\t\t<form method=\"post\" action=\"\" autocomplete=\"off\">\n\t\t\t<div class=\"um-row _um_row_1 \" style=\"margin: 0 0 30px 0;\"><div class=\"um-col-1\"><div  id=\"um_field_6_username\" class=\"um-field um-field-text  um-field-username um-field-text um-field-type_text\" data-key=\"username\"><div class=\"um-field-label\"><label for=\"username-6\">Username or E-mail<span class=\"um-req\" title=\"Obligatorio\">*<\/span><\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"username-6\" id=\"username-6\" value=\"\" placeholder=\"\" data-validate=\"unique_username_or_email\" data-key=\"username\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_6_user_password\" class=\"um-field um-field-password  um-field-user_password um-field-password um-field-type_password\" data-key=\"user_password\"><div class=\"um-field-label\"><label for=\"user_password-6\">Contrase\u00f1a<span class=\"um-req\" title=\"Obligatorio\">*<\/span><\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><div class=\"um-field-area-password\">\n\t\t\t\t\t\t\t\t\t<input class=\"um-form-field valid \" type=\"password\" name=\"user_password-6\" id=\"user_password-6\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"user_password\"  aria-invalid=\"false\" \/>\n\t\t\t\t\t\t\t\t\t<span class=\"um-toggle-password\"><i class=\"um-icon-eye\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/div>\t<input type=\"hidden\" name=\"form_id\" id=\"form_id_6\" value=\"6\" \/>\n\t\t<p class=\"um_request_name\">\n\t\t<label for=\"um_request_6\">Only fill in if you are not human<\/label>\n\t\t<input type=\"hidden\" name=\"um_request\" id=\"um_request_6\" class=\"input\" value=\"\" size=\"25\" autocomplete=\"off\" \/>\n\t<\/p>\n\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"7119904b54\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/Intranet\/wp-json\/wp\/v2\/pages\/12\" \/>\n\t<div class=\"um-col-alt\">\n\n\t\t\n\n\t\t\t<div class=\"um-field um-field-c\">\n\t\t\t\t<div class=\"um-field-area\">\n\t\t\t\t\t<label class=\"um-field-checkbox\">\n\t\t\t\t\t\t<input type=\"checkbox\" name=\"rememberme\" value=\"1\"  \/>\n\t\t\t\t\t\t<span class=\"um-field-checkbox-state\"><i class=\"um-icon-android-checkbox-outline-blank\"><\/i><\/span>\n\t\t\t\t\t\t<span class=\"um-field-checkbox-option\"> Mantenerme conectado<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"um-clear\"><\/div>\n\t\t\n\t\t\t<div class=\"um-center\">\n\t\t\t\t<input type=\"submit\" value=\"Iniciar sesi\u00f3n\" class=\"um-button\" id=\"um-submit-btn\" \/>\n\t\t\t<\/div>\n\n\t\t\n\t\t<div class=\"um-clear\"><\/div>\n\n\t<\/div>\n\n\t\n\t<div class=\"um-col-alt-b\">\n\t\t<a href=\"https:\/\/ipsucaldas.com\/Intranet\/password-reset\/\" class=\"um-link-alt\">\n\t\t\t\u00bfHas olvidado tu contrase\u00f1a?\t\t<\/a>\n\t<\/div>\n\n\t\t\t<\/form>\n\t<\/div>\n<\/div>\n<style>\n\t\t\t.um-6.um {\n\t\t\tmax-width: 100%;\n\t\t}\n\t\t<\/style>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Inicio de sesi\u00f3n Inicia sesi\u00f3n para ingresar la Intranet de la Corporaci\u00f3n IPS Universitaria de Caldas.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":15,"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":326,"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/pages\/12\/revisions\/326"}],"wp:attachment":[{"href":"https:\/\/ipsucaldas.com\/Intranet\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}